{"id":75670,"date":"2026-09-01T16:43:18","date_gmt":"2026-09-01T08:43:18","guid":{"rendered":"https:\/\/www.hsu.edu.hk\/?p=75670"},"modified":"2026-09-02T09:45:44","modified_gmt":"2026-09-02T01:45:44","slug":"professor-joshua-mok-assumes-office-as-hsuhks-new-president-embarks-on-a-new-chapter-with-the-university-community","status":"publish","type":"post","link":"https:\/\/www.hsu.edu.hk\/en\/professor-joshua-mok-assumes-office-as-hsuhks-new-president-embarks-on-a-new-chapter-with-the-university-community\/","title":{"rendered":"Professor Joshua Mok assumes office as HSUHK\u2019s new President and embarks on a new chapter with the University community"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"75670\" class=\"elementor elementor-75670\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08fe32d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08fe32d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-464c7f5\" data-id=\"464c7f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99c3c7d elementor-widget elementor-widget-text-editor\" data-id=\"99c3c7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><\/p>\n<p><strong>1 September 2026&nbsp;<\/strong><\/p>\n<p class=\"x_elementToProof\" data-olk-copy-source=\"MessageBody\">Professor Joshua Mok Ka-ho officially assumed office as the new President of The Hang Seng University of Hong Kong (HSUHK) today. In a letter and a welcome video message issued to staff, students and alumni this morning, Professor Mok said he was honoured to lead this vibrant university community into a new chapter and looked forward to working hand in hand with members of the Board of Governors, students, faculty, staff and alumni as the University embarks on a new chapter of development.<\/p>\n<p>He encouraged new students to explore widely, learn with curiosity, and make the most of the diverse learning and development opportunities that HSUHK offers. He also welcomed newly appointed colleagues, whose expertise, energy and commitment will further enrich the University\u2019s academic community and help shape the next stage of the University\u2019s development.<\/p>\n<p>Professor Mok said, \u201cHSUHK\u2019s educational philosophy is closely aligned with the Hong Kong Government\u2019s goal of developing Hong Kong into an international education hub. We do not see this simply as a policy direction to follow, but as a vision that resonates deeply with our mission as a university rooted in Hong Kong and connected to the world. We believe Hong Kong is well positioned to offer students a distinctive learning experience that combines an international outlook, an appreciation of Chinese culture, professional preparation, and access to opportunities across the Greater Bay Area and beyond.\u201d<\/p>\n<p>In his welcome video message on the first day of the new academic year, Professor Mok emphasised that higher education should not only impart professional knowledge, but also nurture caring professional leaders with a global vision, a strong sense of responsibility, and a commitment to serving society. He said, \u201cAs artificial intelligence and emerging technologies reshape our world, universities must go beyond equipping students with new technological skills. We must also impart knowledge guided by the spirit of \u2018Care for learning, Learning to Care\u2019, enabling students to apply technology wisely and responsibly to address pressing societal needs and human challenges.\u201d<\/p>\n<p>In addition, HSUHK conferred the title of President Emeritus on Professor Simon S M Ho, the immediate past President. The University also named an orchid tree on campus in his honour in recognition of his profound contributions to HSUHK\u2019s development.<\/p>\n<p>Letter from Professor Mok to the HSUHK Community: click&nbsp;<a href=\"https:\/\/hsuhk.sharepoint.com\/:b:\/t\/CPAO-Intranet\/IQB8-vTmsjh2TpEu6gT9Xl33AcDBxP6WLvZaXCuclw-WlZY?e=CxphZR\"><span style=\"color: #0000ff;\">here<\/span><\/a><br>Professor Mok\u2019s welcome message video: click&nbsp;<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/youtu.be\/u_qyGekics0\">here<\/a><\/span><\/p>\n<p><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53eb361 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53eb361\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9272df0\" data-id=\"9272df0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2237e4c elementor-widget elementor-widget-image\" data-id=\"2237e4c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"600\" height=\"426\" src=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-1-1140x810.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-1-1140x810.jpg 1140w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-1-768x545.jpg 768w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-1-1536x1091.jpg 1536w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-1-2048x1455.jpg 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c615b3 elementor-widget elementor-widget-image\" data-id=\"4c615b3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"600\" height=\"400\" src=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-2-1140x760.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-2-1140x760.jpg 1140w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-2-768x512.jpg 768w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-2-1536x1024.jpg 1536w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-2-2048x1365.jpg 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24a4995 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"24a4995\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2b5d9c0\" data-id=\"2b5d9c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce9ca89 elementor-widget elementor-widget-image\" data-id=\"ce9ca89\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"600\" height=\"400\" src=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-3-1140x760.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-3-1140x760.jpg 1140w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-3-768x512.jpg 768w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-3-1536x1024.jpg 1536w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-3-2048x1365.jpg 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79984ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79984ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52dbfea\" data-id=\"52dbfea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-435dfa6 elementor-widget elementor-widget-image\" data-id=\"435dfa6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"600\" height=\"397\" src=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-4-1140x755.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-4-1140x755.jpg 1140w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-4-768x508.jpg 768w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-4-1536x1017.jpg 1536w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-4-2048x1356.jpg 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Photo 1 \u2013 4: HSUHK\u2019s new President, Professor Joshua Mok, visits various parts of the campus and interacts with staff and students, bringing energy and enthusiasm to the new academic year.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-679856d elementor-widget elementor-widget-image\" data-id=\"679856d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"600\" height=\"458\" src=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-5-1140x871.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-5-1140x871.jpg 1140w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-5-768x587.jpg 768w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-5-1536x1173.jpg 1536w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-5-2048x1564.jpg 2048w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-5-255x195.jpg 255w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-5-275x210.jpg 275w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d703761 elementor-widget elementor-widget-image\" data-id=\"d703761\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"600\" height=\"450\" src=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-6-1140x855.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-6-1140x855.jpeg 1140w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-6-768x576.jpeg 768w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-6-1536x1152.jpeg 1536w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-6-2048x1536.jpeg 2048w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-6-360x270.jpeg 360w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95e5eb3 elementor-widget elementor-widget-image\" data-id=\"95e5eb3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img width=\"600\" height=\"450\" src=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-7-1140x855.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-7-1140x855.jpeg 1140w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-7-768x576.jpeg 768w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-7-1536x1152.jpeg 1536w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-7-2048x1536.jpeg 2048w, https:\/\/www.hsu.edu.hk\/wp-content\/uploads\/2026\/09\/20260901_Professor-Joshua-Mok-assumes-office-as-HSUHKs-new-President_Photo-7-360x270.jpeg 360w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Photo 5 - 7: HSUHK hosts its opening-day carnival, HSUHK Fiesta. Professor Joshua Mok, together with members of the senior management team, prepare Hong Kong-style snacks for staff and students, bringing energy and a warm welcome to the new academic year.<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":74,"featured_media":75675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"categories":[144,10,444,163,76],"tags":[],"topics":[228,231],"month":[461],"_links":{"self":[{"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/posts\/75670"}],"collection":[{"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/comments?post=75670"}],"version-history":[{"count":18,"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/posts\/75670\/revisions"}],"predecessor-version":[{"id":75715,"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/posts\/75670\/revisions\/75715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/media\/75675"}],"wp:attachment":[{"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/media?parent=75670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/categories?post=75670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/tags?post=75670"},{"taxonomy":"topics","embeddable":true,"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/topics?post=75670"},{"taxonomy":"month","embeddable":true,"href":"https:\/\/www.hsu.edu.hk\/en\/wp-json\/wp\/v2\/month?post=75670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}